{"id":35,"count":74,"description":"Linguagem er\u00f3tica direta, com descri\u00e7\u00e3o clara dos atos, do corpo e da intensidade da cena.","link":"https:\/\/desejosintensos.com\/index.php\/tag\/explicito\/","name":"expl\u00edcito","slug":"explicito","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/tags\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/posts?tags=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}