{"id":58,"count":8,"description":"Fantasia conjugal em que o parceiro sabe, observa ou participa da entrega da parceira a outro.","link":"https:\/\/desejosintensos.com\/index.php\/tag\/cuckold\/","name":"cuckold","slug":"cuckold","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/tags\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/desejosintensos.com\/index.php\/wp-json\/wp\/v2\/posts?tags=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}